{"id":17,"date":"2016-01-13T19:55:52","date_gmt":"2016-01-13T19:55:52","guid":{"rendered":"http:\/\/ecolos.wpengine.com\/?page_id=17&#038;lang=fr"},"modified":"2026-05-08T04:03:44","modified_gmt":"2026-05-08T04:03:44","slug":"accueil","status":"publish","type":"page","link":"https:\/\/ecolos.ca\/fr\/","title":{"rendered":"Accueil"},"content":{"rendered":"<p style=\"text-align: left;\"><div class=\"fusion-fullwidth fullwidth-box fusion-fullwidth-1  fusion-parallax-none nonhundred-percent-fullwidth\" style=\"border-color:#f7f7f7;border-bottom-width: 0px;border-top-width: 0px;border-bottom-style: solid;border-top-style: solid;padding-bottom:40px;padding-top:40px;padding-left:20px;padding-right:20px;\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-fullwidth-1 {\n                            padding-left: 20px !important;\n                            padding-right: 20px !important;\n                        }<\/style><div class=\"fusion-row\"><h3 class=\"greenText\">\n<h3\/>\n<h1 class=\"greenText\">Le traversier Ecolos<\/h1>\n<p>Le traversier Ecolos est un moyen de transport public \u00e9cologique. Il offre un service de traversier sur la rivi\u00e8re Ottawa (Outaouais) entre l\u2019\u00eele de Clarence et la municipalit\u00e9 de Thurso. Ce traversier est vraiment unique puisque son syst\u00e8me de propulsion n\u2019\u00e9met aucune \u00e9mission ou pollution, fonctionnant totalement \u00e0 partir de batteries, qui elles, sont recharg\u00e9es \u00e0 partir du circuit \u00e9lectrique conventionnel. Le syst\u00e8me de propulsion au di\u00e9sel utilis\u00e9 originalement par le Minist\u00e8re des Transports de l\u2019Ontario a \u00e9t\u00e9 \u00e9limin\u00e9 et remplac\u00e9 par un syst\u00e8me \u00e0 propulsion \u00e9lectrique. Le traversier a \u00e9t\u00e9 \u00e9largi pour recevoir les batteries ce qui a permis \u00e9galement d\u2019\u00e9liminer les contrepoids. La timonerie fut remplac\u00e9e pour en am\u00e9liorer la visibilit\u00e9 et le confort.<\/p>\n<p>Ecolos est un traversier \u00e0 c\u00e2bles ce qui en am\u00e9liore l\u2019efficacit\u00e9 car il n\u2019a pas d\u2019h\u00e9lice, donc il n\u2019agite pas l\u2019eau, ses moteurs sont plus petits, et il produit moins de bruit qu\u2019un traversier conventionnel.<\/p>\n<\/div><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-17","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accueil - Ecolos<\/title>\n<meta name=\"description\" content=\"Le traversier Ecolos est un moyen de transport public \u00e9cologique. Il offre un service de traversier sur la rivi\u00e8re Ottawa (Outaouais) entre l\u2019\u00eele de Clarence et la municipalit\u00e9 de Thurso. Ce traversier est vraiment unique puisque\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecolos.ca\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accueil - Ecolos\" \/>\n<meta property=\"og:description\" content=\"Le traversier Ecolos est un moyen de transport public \u00e9cologique. Il offre un service de traversier sur la rivi\u00e8re Ottawa (Outaouais) entre l\u2019\u00eele de Clarence et la municipalit\u00e9 de Thurso. Ce traversier est vraiment unique puisque\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecolos.ca\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecolos\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T04:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolos.ca\\\/fr\\\/\",\"url\":\"https:\\\/\\\/ecolos.ca\\\/fr\\\/\",\"name\":\"Accueil - Ecolos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolos.ca\\\/#website\"},\"datePublished\":\"2016-01-13T19:55:52+00:00\",\"dateModified\":\"2026-05-08T04:03:44+00:00\",\"description\":\"Le traversier Ecolos est un moyen de transport public \u00e9cologique. Il offre un service de traversier sur la rivi\u00e8re Ottawa (Outaouais) entre l\u2019\u00eele de Clarence et la municipalit\u00e9 de Thurso. Ce traversier est vraiment unique puisque\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolos.ca\\\/fr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecolos.ca\\\/fr\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolos.ca\\\/fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecolos.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolos.ca\\\/#website\",\"url\":\"https:\\\/\\\/ecolos.ca\\\/\",\"name\":\"Ecolos\",\"description\":\"Ecolos\",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolos.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecolos.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolos.ca\\\/#organization\",\"name\":\"Ecolos\",\"url\":\"https:\\\/\\\/ecolos.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ecolos.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ecolos.ca\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/logo_2.png\",\"contentUrl\":\"https:\\\/\\\/ecolos.ca\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/logo_2.png\",\"width\":208,\"height\":47,\"caption\":\"Ecolos\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolos.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accueil - Ecolos","description":"Le traversier Ecolos est un moyen de transport public \u00e9cologique. Il offre un service de traversier sur la rivi\u00e8re Ottawa (Outaouais) entre l\u2019\u00eele de Clarence et la municipalit\u00e9 de Thurso. Ce traversier est vraiment unique puisque","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecolos.ca\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Accueil - Ecolos","og_description":"Le traversier Ecolos est un moyen de transport public \u00e9cologique. Il offre un service de traversier sur la rivi\u00e8re Ottawa (Outaouais) entre l\u2019\u00eele de Clarence et la municipalit\u00e9 de Thurso. Ce traversier est vraiment unique puisque","og_url":"https:\/\/ecolos.ca\/fr\/","og_site_name":"Ecolos","article_modified_time":"2026-05-08T04:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecolos.ca\/fr\/","url":"https:\/\/ecolos.ca\/fr\/","name":"Accueil - Ecolos","isPartOf":{"@id":"https:\/\/ecolos.ca\/#website"},"datePublished":"2016-01-13T19:55:52+00:00","dateModified":"2026-05-08T04:03:44+00:00","description":"Le traversier Ecolos est un moyen de transport public \u00e9cologique. Il offre un service de traversier sur la rivi\u00e8re Ottawa (Outaouais) entre l\u2019\u00eele de Clarence et la municipalit\u00e9 de Thurso. Ce traversier est vraiment unique puisque","breadcrumb":{"@id":"https:\/\/ecolos.ca\/fr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecolos.ca\/fr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ecolos.ca\/fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecolos.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Accueil"}]},{"@type":"WebSite","@id":"https:\/\/ecolos.ca\/#website","url":"https:\/\/ecolos.ca\/","name":"Ecolos","description":"Ecolos","publisher":{"@id":"https:\/\/ecolos.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecolos.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ecolos.ca\/#organization","name":"Ecolos","url":"https:\/\/ecolos.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ecolos.ca\/#\/schema\/logo\/image\/","url":"https:\/\/ecolos.ca\/wp-content\/uploads\/2016\/01\/logo_2.png","contentUrl":"https:\/\/ecolos.ca\/wp-content\/uploads\/2016\/01\/logo_2.png","width":208,"height":47,"caption":"Ecolos"},"image":{"@id":"https:\/\/ecolos.ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ecolos.ca\/fr\/wp-json\/wp\/v2\/pages\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecolos.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ecolos.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ecolos.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecolos.ca\/fr\/wp-json\/wp\/v2\/comments?post=17"}],"version-history":[{"count":11,"href":"https:\/\/ecolos.ca\/fr\/wp-json\/wp\/v2\/pages\/17\/revisions"}],"predecessor-version":[{"id":357,"href":"https:\/\/ecolos.ca\/fr\/wp-json\/wp\/v2\/pages\/17\/revisions\/357"}],"wp:attachment":[{"href":"https:\/\/ecolos.ca\/fr\/wp-json\/wp\/v2\/media?parent=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}